{"id":322,"date":"2015-12-04T12:16:04","date_gmt":"2015-12-04T10:16:04","guid":{"rendered":"http:\/\/www.nordstein.at\/literatur\/?p=322"},"modified":"2015-12-04T12:16:04","modified_gmt":"2015-12-04T10:16:04","slug":"lumikkis-schwester","status":"publish","type":"post","link":"https:\/\/www.nordstein.at\/literatur\/lumikkis-schwester\/","title":{"rendered":"Lumikkis Schwester"},"content":{"rendered":"<p><a href=\"http:\/\/www.nordstein.at\/literatur\/wp-content\/uploads\/simukka_schwarz.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-323 alignright\" src=\"http:\/\/www.nordstein.at\/literatur\/wp-content\/uploads\/simukka_schwarz-300x300.jpg\" alt=\"simukka_schwarz\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.nordstein.at\/literatur\/wp-content\/uploads\/simukka_schwarz-300x300.jpg 300w, https:\/\/www.nordstein.at\/literatur\/wp-content\/uploads\/simukka_schwarz-150x150.jpg 150w, https:\/\/www.nordstein.at\/literatur\/wp-content\/uploads\/simukka_schwarz-1024x1024.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Endlich ist er da, der dritte Band der Lumikki-Trilogie der finnischen Autorin Salla Simukka. Und es wird, wie zu erwarten war, schaurig und blutig. Lumikki hat sich gerade erst von den Erlebnissen in Prag erholt. Der Herbst war etwas ruhiger und sie ist neu verliebt, als sie in der Vorweihnachtszeit pl\u00f6tzlich r\u00e4tselhafte Botschaften bekommt. Jemand wei\u00df nicht nur alles \u00fcber ihr derzeitiges Leben, weil er sie anscheinend beobachtet, sondern auch \u00fcber die geheimnisvollen Ereignisse in ihrer Kindheit, an die sie selbst nur vage Erinnerungen hat. Hatte sie wirklich eine Schwester? Die Botschaften werden zu Drohungen und Lumikki wagt nicht, sich jemandem anzuvertrauen. Dann taucht auch ihre alte Liebe Flamme wieder auf. Doch wem kann sie noch vertrauen? Das Buch ist spannend, die Aufl\u00f6sung des Spannungsbogens am Ende schl\u00fcssig. Leider kann der Band aber wie schon der zweite Teil der Trilogie nicht hundertprozentig an die literarische Qualit\u00e4t des ersten Bandes anschlie\u00dfen. Mit \u201eSo rot wie Blut\u201c wurde Simukka \u2013 v\u00f6llig zu Recht \u2013 \u00fcber Nacht ber\u00fchmt, die Rechte f\u00fcr die Trilogie wurden schnell in zahlreiche L\u00e4nder verkauft und damit wohl zu viel Zeitdruck erzeugt. Dennoch eine gro\u00dfe Lese- und Geschenkempfehlung f\u00fcr alle, die Spannung und Nervenkitzel suchen \u2013 auch ohne Fantasy.<\/p>\n<p><b>Salla Simukka: So schwarz wie Ebenholz. <\/b>Roman. Aus dem Finnischen von Elina Kritzokat.\u00a0197 Seiten, Arena, W\u00fcrzburg 2015\u00a0\u00a0EUR\u00a0 14,40<\/p>\n<p>erstmals erschienen in\u00a0<a href=\"http:\/\/weiberdiwan.at\/lumikkis-schwester\/\" target=\"_blank\">WeiberDiwan 02\/2015<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Endlich ist er da, der dritte Band der Lumikki-Trilogie der finnischen Autorin Salla Simukka. Und es wird, wie zu erwarten war, schaurig und blutig. Lumikki hat sich gerade erst von den Erlebnissen in Prag erholt. Der Herbst war etwas ruhiger und sie ist neu verliebt, als sie in der Vorweihnachtszeit pl\u00f6tzlich r\u00e4tselhafte Botschaften bekommt. Jemand &hellip; <a href=\"https:\/\/www.nordstein.at\/literatur\/lumikkis-schwester\/\" class=\"more-link\"><span class=\"screen-reader-text\">Lumikkis Schwester<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[12,18,23],"_links":{"self":[{"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/posts\/322"}],"collection":[{"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/comments?post=322"}],"version-history":[{"count":1,"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/posts\/322\/revisions"}],"predecessor-version":[{"id":324,"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/posts\/322\/revisions\/324"}],"wp:attachment":[{"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/media?parent=322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/categories?post=322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/tags?post=322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}