{"id":4,"count":33,"description":"","link":"https:\/\/www.nordstein.at\/literatur\/category\/romane\/","name":"Romane und Novellen","slug":"romane","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/categories\/4"}],"collection":[{"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.nordstein.at\/literatur\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}